{"id":1760,"date":"2022-05-09T03:15:12","date_gmt":"2022-05-09T03:15:12","guid":{"rendered":"https:\/\/arquetipo.us\/?post_type=projects&#038;p=1760"},"modified":"2025-06-18T21:46:28","modified_gmt":"2025-06-18T21:46:28","slug":"vajestma","status":"publish","type":"projects","link":"https:\/\/arquetipo.us\/es\/projects\/vajestma\/","title":{"rendered":"Vajestma"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1760\" class=\"elementor elementor-1760\" data-elementor-post-type=\"projects\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd9c205 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"cd9c205\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dfa90a exad-glass-effect-no exad-sticky-section-no\" data-id=\"9dfa90a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dccded1 elementor-icon-list--layout-inline elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"dccded1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\/?page_id=2287\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nosotros<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\/work\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Proyectos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\/contact-us\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contacto<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7b3d4a elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e7b3d4a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0675114 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0675114\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-971aace elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"971aace\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a0aa626 exad-glass-effect-no exad-sticky-section-no\" data-id=\"a0aa626\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d43881 elementor-widget__width-auto exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3d43881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vajestma<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe32bcc elementor-widget__width-auto elementor-hidden-desktop exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-html\" data-id=\"fe32bcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"container\">\n        <span class=\"material-symbols-sharp\" id=\"banner-1-btn\"> south<\/span>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2660679 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2660679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vajestma es una empresa con un sentido \u00fanico del espacio, la forma y la construcci\u00f3n. Ellos construyen con la perfecci\u00f3n y el mejor lugar para vivir en mente.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27c4f43 column exad-glass-effect-no exad-sticky-section-no\" data-id=\"27c4f43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40255e8 elementor-widget__width-auto elementor-hidden-tablet elementor-hidden-mobile exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-html\" data-id=\"40255e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"container\">\n        <span class=\"material-symbols-sharp\" id=\"banner-1-btn\"> south<\/span>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5550554 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"5550554\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e78c180 exad-glass-effect-no exad-sticky-section-no\" data-id=\"e78c180\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c2d9d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"2c2d9d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a1e732d exad-glass-effect-no exad-sticky-section-no\" data-id=\"a1e732d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30c65d7 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"30c65d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alcance:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-aada067 exad-glass-effect-no exad-sticky-section-no\" data-id=\"aada067\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e40c9a elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"4e40c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Logo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Experiencia de Marca<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Valores de la marca<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voz de marca y eslogan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ece5ba1 exad-glass-effect-no exad-sticky-section-no\" data-id=\"ece5ba1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ee1f9f elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"5ee1f9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ilustraciones y Patrones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-circle\" data-md-icon=\"circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Campa\u00f1a para Redes Sociales<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b736460 exad-glass-effect-no exad-sticky-section-no\" data-id=\"b736460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85c2304 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"85c2304\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7069229 exad-glass-effect-no exad-sticky-section-no\" data-id=\"7069229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e54bd22 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e54bd22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-69211bf exad-glass-effect-no exad-sticky-section-no\" data-id=\"69211bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc644ae elementor-widget__width-inherit exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"fc644ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg\" class=\"attachment-full size-full wp-image-2171\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg 1920w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy-300x169.jpg 300w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy-1024x576.jpg 1024w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy-768x432.jpg 768w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3450d74 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"3450d74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-25de47d exad-glass-effect-no exad-sticky-section-no\" data-id=\"25de47d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebedb7f elementor-widget__width-inherit exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"ebedb7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy.jpg\" class=\"attachment-full size-full wp-image-2169\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy.jpg 1920w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy-300x169.jpg 300w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy-1024x576.jpg 1024w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy-768x432.jpg 768w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Construction-copy-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55d3733 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"55d3733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-82788c7 exad-glass-effect-no exad-sticky-section-no\" data-id=\"82788c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb34d83 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"cb34d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-copy-4.jpg\" class=\"attachment-full size-full wp-image-2170\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-copy-4.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-copy-4-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-copy-4-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-copy-4-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-91cbc5b exad-glass-effect-no exad-sticky-section-no\" data-id=\"91cbc5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d8c57 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e0d8c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-2-copy-1.jpg\" class=\"attachment-full size-full wp-image-2168\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-2-copy-1.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-2-copy-1-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-2-copy-1-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-2-copy-1-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e09dfd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e09dfd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3196a46 exad-glass-effect-no exad-sticky-section-no\" data-id=\"3196a46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7b1ce6 elementor-widget__width-inherit exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e7b1ce6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy.jpg\" class=\"attachment-full size-full wp-image-2172\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy.jpg 1920w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy-300x169.jpg 300w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy-1024x576.jpg 1024w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy-768x432.jpg 768w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Sobre-copy-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9303142 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"9303142\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-10ac096 exad-glass-effect-no exad-sticky-section-no\" data-id=\"10ac096\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0314530 elementor-widget__width-inherit exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"0314530\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy.jpg\" class=\"attachment-full size-full wp-image-2165\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy.jpg 1920w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy-300x169.jpg 300w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy-1024x576.jpg 1024w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy-768x432.jpg 768w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Carpeta-copy-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f055924 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"f055924\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5700f28 exad-glass-effect-no exad-sticky-section-no\" data-id=\"5700f28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bd047b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7bd047b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-copy.jpg\" class=\"attachment-full size-full wp-image-2166\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-copy.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-copy-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-copy-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-copy-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee3da98 exad-glass-effect-no exad-sticky-section-no\" data-id=\"ee3da98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44aa93a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"44aa93a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-Vajestma-copy.jpg\" class=\"attachment-full size-full wp-image-2167\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-Vajestma-copy.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-Vajestma-copy-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-Vajestma-copy-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Casco-Vajestma-copy-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d5c8f45 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"d5c8f45\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2fce441 exad-glass-effect-no exad-sticky-section-no\" data-id=\"2fce441\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f653fb4 elementor-widget__width-inherit exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"f653fb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1.jpg\" class=\"attachment-full size-full wp-image-2164\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1.jpg 1920w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1-300x169.jpg 300w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1-1024x576.jpg 1024w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1-768x432.jpg 768w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Billboard-copy-1-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71881b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"71881b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6da9d11 exad-glass-effect-no exad-sticky-section-no\" data-id=\"6da9d11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab91676 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"ab91676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/web-1-copy.jpg\" class=\"attachment-full size-full wp-image-2174\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/web-1-copy.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/web-1-copy-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/web-1-copy-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/web-1-copy-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-91d8f4a exad-glass-effect-no exad-sticky-section-no\" data-id=\"91d8f4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1135e25 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"1135e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"946\" height=\"1080\" src=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/social-media-copy-1.jpg\" class=\"attachment-full size-full wp-image-2173\" alt=\"\" srcset=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/social-media-copy-1.jpg 946w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/social-media-copy-1-263x300.jpg 263w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/social-media-copy-1-897x1024.jpg 897w, https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/social-media-copy-1-768x877.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e19f2ce elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e19f2ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-119375b exad-glass-effect-no exad-sticky-section-no\" data-id=\"119375b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58baacc exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-post-navigation\" data-id=\"58baacc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\/projects\/coletta-gelato\/\" rel=\"prev\"><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Siguiente<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/arquetipo.us\/es\/projects\/ambered-ember\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\"><\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00ce9a2 elementor-section-full_width elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"00ce9a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82960b4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"82960b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2581a74 elementor-widget__width-auto elementor-fixed elementor-view-default exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"2581a74\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"popup-btn-4\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjIwNiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"template":"","categories_projects":[21],"class_list":["post-1760","projects","type-projects","status-publish","hentry","categories_projects-corporate"],"acf":{"short_description":"They build with perfection the best place to live.","full_description":"Vajestma is a company with a unique sense of space, form, and construction. They build with perfection and the best place to live in mind.","cover_3_4":1761,"cover_3_4_fallback":1761,"cover_16_9":3026,"cover_16_9_fallback":3026},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vajestma - Arquetipo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arquetipo.us\/es\/projects\/vajestma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vajestma - Arquetipo\" \/>\n<meta property=\"og:description\" content=\"Home Our Studio Work Contact south south Capabilities: Logo Brand Experience Brand Values Brand Voice &amp; Tagline Illustration and Patterns Social Media Roll Up Campaign\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arquetipo.us\/es\/projects\/vajestma\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquetipo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T21:46:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/\",\"url\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/\",\"name\":\"Vajestma - Arquetipo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arquetipo.us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arquetipo.us\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-Fondo-copy.jpg\",\"datePublished\":\"2022-05-09T03:15:12+00:00\",\"dateModified\":\"2025-06-18T21:46:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arquetipo.us\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-Fondo-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/arquetipo.us\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-Fondo-copy.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arquetipo.us\\\/projects\\\/vajestma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arquetipo.us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/arquetipo.us\\\/Projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vajestma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arquetipo.us\\\/#website\",\"url\":\"https:\\\/\\\/arquetipo.us\\\/\",\"name\":\"Arquetipo\",\"description\":\"Branding &amp; Design Agency in Miami\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arquetipo.us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vajestma - Arquetipo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arquetipo.us\/es\/projects\/vajestma\/","og_locale":"es_ES","og_type":"article","og_title":"Vajestma - Arquetipo","og_description":"Home Our Studio Work Contact south south Capabilities: Logo Brand Experience Brand Values Brand Voice &amp; Tagline Illustration and Patterns Social Media Roll Up Campaign","og_url":"https:\/\/arquetipo.us\/es\/projects\/vajestma\/","og_site_name":"Arquetipo","article_modified_time":"2025-06-18T21:46:28+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arquetipo.us\/projects\/vajestma\/","url":"https:\/\/arquetipo.us\/projects\/vajestma\/","name":"Vajestma - Arquetipo","isPartOf":{"@id":"https:\/\/arquetipo.us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arquetipo.us\/projects\/vajestma\/#primaryimage"},"image":{"@id":"https:\/\/arquetipo.us\/projects\/vajestma\/#primaryimage"},"thumbnailUrl":"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg","datePublished":"2022-05-09T03:15:12+00:00","dateModified":"2025-06-18T21:46:28+00:00","breadcrumb":{"@id":"https:\/\/arquetipo.us\/projects\/vajestma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arquetipo.us\/projects\/vajestma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arquetipo.us\/projects\/vajestma\/#primaryimage","url":"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg","contentUrl":"https:\/\/arquetipo.us\/wp-content\/uploads\/2022\/05\/Logo-Fondo-copy.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/arquetipo.us\/projects\/vajestma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arquetipo.us\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/arquetipo.us\/Projects\/"},{"@type":"ListItem","position":3,"name":"Vajestma"}]},{"@type":"WebSite","@id":"https:\/\/arquetipo.us\/#website","url":"https:\/\/arquetipo.us\/","name":"Arquetipo","description":"Branding &amp; Design Agency in Miami","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arquetipo.us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/projects\/1760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/types\/projects"}],"version-history":[{"count":5,"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/projects\/1760\/revisions"}],"predecessor-version":[{"id":9357,"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/projects\/1760\/revisions\/9357"}],"wp:attachment":[{"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/media?parent=1760"}],"wp:term":[{"taxonomy":"categories_projects","embeddable":true,"href":"https:\/\/arquetipo.us\/es\/wp-json\/wp\/v2\/categories_projects?post=1760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}